{"id":1744,"date":"2026-08-13T07:18:09","date_gmt":"2026-08-13T01:48:09","guid":{"rendered":"https:\/\/indusherbal.com\/lang\/ur\/blog\/%d8%a7%db%8c%da%a9-%da%86%db%8c%d8%ae%d8%8c-%d9%be%da%be%d8%b1-%d9%85%d8%b3%da%a9%d8%b1%d8%a7%db%81%d9%b9%d8%9f-%da%86%db%8c%d8%ae%d9%86%db%92-%da%a9%db%8c-%d8%b9%d8%ac%db%8c%d8%a8-%d8%b3%d8%a7%d8%a6\/"},"modified":"2026-08-13T07:18:09","modified_gmt":"2026-08-13T01:48:09","slug":"%d8%a7%db%8c%da%a9-%da%86%db%8c%d8%ae%d8%8c-%d9%be%da%be%d8%b1-%d9%85%d8%b3%da%a9%d8%b1%d8%a7%db%81%d9%b9%d8%9f-%da%86%db%8c%d8%ae%d9%86%db%92-%da%a9%db%8c-%d8%b9%d8%ac%db%8c%d8%a8-%d8%b3%d8%a7%d8%a6","status":"publish","type":"post","link":"https:\/\/indusherbal.com\/lang\/ur\/blog\/%d8%a7%db%8c%da%a9-%da%86%db%8c%d8%ae%d8%8c-%d9%be%da%be%d8%b1-%d9%85%d8%b3%da%a9%d8%b1%d8%a7%db%81%d9%b9%d8%9f-%da%86%db%8c%d8%ae%d9%86%db%92-%da%a9%db%8c-%d8%b9%d8%ac%db%8c%d8%a8-%d8%b3%d8%a7%d8%a6\/","title":{"rendered":"\u0627\u06cc\u06a9 \u0686\u06cc\u062e\u060c \u067e\u06be\u0631 \u0645\u0633\u06a9\u0631\u0627\u06c1\u0679\u061f \u0686\u06cc\u062e\u0646\u06d2 \u06a9\u06cc \u0639\u062c\u06cc\u0628 \u0633\u0627\u0626\u0646\u0633"},"content":{"rendered":"<p>\u06a9\u06cc\u0627 \u0622\u067e \u0646\u06d2 \u06a9\u0628\u06be\u06cc \u0645\u062d\u0633\u0648\u0633 \u06a9\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062f\u0644 \u0645\u06cc\u06ba \u062f\u0628\u0627 \u062f\u0628\u0627\u0624 \u0627\u062a\u0646\u0627 \u0628\u0691\u06be \u062c\u0627\u0626\u06d2 \u06a9\u06c1 \u0633\u0627\u0646\u0633 \u0644\u06cc\u0646\u0627 \u0628\u06be\u06cc \u0645\u0634\u06a9\u0644 \u06c1\u0648 \u062c\u0627\u0626\u06d2\u061f \u0648\u06c1 \u0644\u0645\u062d\u06c1 \u062c\u0628 \u0622\u067e \u0628\u0633 \u0627\u06cc\u06a9 \u0644\u0645\u0628\u06cc\u060c \u0628\u0644\u0646\u062f \u0622\u0648\u0627\u0632 \u0645\u06cc\u06ba \u0686\u06cc\u062e\u0646\u0627 \u0686\u0627\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0686\u0627\u06c1\u06d2 \u0648\u06c1 \u062a\u06a9\u06cc\u06d2 \u0645\u06cc\u06ba \u06c1\u06cc \u06a9\u06cc\u0648\u06ba \u0646\u06c1 \u06c1\u0648\u061f \u06cc\u06c1 \u0627\u062d\u0633\u0627\u0633 \u0627\u0646\u062a\u06c1\u0627\u0626\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc \u06c1\u06d2\u060c \u0627\u0648\u0631 \u0627\u0633 \u06a9\u0627 \u062a\u0639\u0644\u0642 \u0628\u0631\u0627\u06c1 \u0631\u0627\u0633\u062a \u06c1\u0645\u0627\u0631\u06d2 \u062f\u0645\u0627\u063a \u06a9\u06d2 \u0627\u06cc\u06a9 \u067e\u0631\u0627\u0633\u0631\u0627\u0631 \u0646\u0638\u0627\u0645 \u0633\u06d2 \u06c1\u06d2 \u062c\u0633\u06d2 \u06c1\u0645 <span style=\"color:#4CAF50; font-weight:bold; text-decoration:underline;\">\u0686\u06cc\u062e \u06a9\u06cc \u0633\u0627\u0626\u0646\u0633<\/span> \u06a9\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4<\/p>\n<p>\u06c1\u0645 \u0627\u06a9\u062b\u0631 \u0686\u06cc\u062e\u0646\u06d2 \u06a9\u0648 \u063a\u0635\u06d2 \u06cc\u0627 \u06a9\u0645\u0632\u0648\u0631\u06cc \u0633\u06d2 \u062c\u0648\u0691 \u062f\u06cc\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0644\u06cc\u06a9\u0646 \u06a9\u06cc\u0627 \u0622\u067e \u062c\u0627\u0646\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u06cc\u06c1 \u0627\u06cc\u06a9 \u0637\u0627\u0642\u062a\u0648\u0631 <span style=\"color:#2196F3; font-weight:bold; text-decoration:underline;\">\u0646\u0641\u0633\u06cc\u0627\u062a\u06cc \u0639\u0644\u0627\u062c<\/span> \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u0648 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u061f \u062d\u0642\u06cc\u0642\u062a \u06cc\u06c1 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06cc\u06a9 \u0686\u06cc\u062e\u060c \u067e\u06be\u0631 \u0645\u0633\u06a9\u0631\u0627\u06c1\u0679\u061f \u0686\u06cc\u062e\u0646\u06d2 \u06a9\u06cc \u0639\u062c\u06cc\u0628 \u0633\u0627\u0626\u0646\u0633 \u0622\u067e \u06a9\u0648 \u062d\u06cc\u0631\u0627\u0646 \u06a9\u0631 \u062f\u06d2 \u06af\u06cc\u06d4 \u06cc\u06c1 \u0635\u0631\u0641 \u0634\u0648\u0631 \u0646\u06c1\u06cc\u06ba\u060c \u0628\u0644\u06a9\u06c1 \u0622\u067e \u06a9\u06d2 \u062c\u0630\u0628\u0627\u062a\u06cc \u0631\u06cc\u0644\u06cc\u0641 \u06a9\u0627 \u0627\u06cc\u06a9 \u0642\u062f\u06cc\u0645\u06cc \u0627\u0648\u0631 \u0645\u0624\u062b\u0631 \u0637\u0631\u06cc\u0642\u06c1 \u06c1\u06d2 \u062c\u0648 \u0635\u062f\u06cc\u0648\u06ba \u0633\u06d2 \u0645\u0648\u062c\u0648\u062f \u06c1\u06d2\u06d4<\/p>\n<p>\u0630\u0631\u0627 \u062a\u0635\u0648\u0631 \u06a9\u06cc\u062c\u06cc\u06d2: \u0622\u067e \u06a9\u0627 \u062f\u0646 \u0628\u06c1\u062a \u0628\u0631\u0627 \u06af\u0632\u0631\u0627 \u06c1\u06d2\u060c \u0622\u0641\u0633 \u0645\u06cc\u06ba \u0628\u0627\u0633 \u0646\u06d2 \u0688\u0627\u0646\u0679\u0627\u060c \u0679\u0631\u06cc\u0641\u06a9 \u0645\u06cc\u06ba \u06af\u06be\u0646\u0679\u0648\u06ba \u067e\u06be\u0646\u0633\u06d2 \u0631\u06c1\u06d2\u060c \u0627\u0648\u0631 \u06af\u06be\u0631 \u067e\u06c1\u0646\u0686\u062a\u06d2 \u06c1\u06cc \u0622\u067e \u06a9\u0648 \u067e\u062a\u06c1 \u0686\u0644\u0627 \u06a9\u06c1 \u0641\u0631\u062c \u06a9\u0627 \u062f\u0631\u0648\u0627\u0632\u06c1 \u06a9\u06be\u0644\u0627 \u067e\u0691\u0627 \u06c1\u06d2\u06d4 \u0627\u06cc\u0633\u06d2 \u0645\u06cc\u06ba \u0622\u067e \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u06a9\u06cc \u06c1\u0648\u0627 \u0628\u0627\u06c1\u0631 \u0646\u06a9\u0644\u0646\u0627 \u0686\u0627\u06c1\u062a\u06cc \u06c1\u06d2\u060c \u0627\u0648\u0631 \u0648\u06c1 \u0631\u0627\u0633\u062a\u06c1 \u06c1\u06d2&#8230; \u0686\u06cc\u062e\u06d4<\/p>\n<p><img data-lazyloaded=\"1\" decoding=\"async\" loading=\"lazy\" style=\"display:block; margin:auto;\" src=\"https:\/\/images.pexels.com\/photos\/8862297\/pexels-photo-8862297.jpeg?auto=compress&#038;cs=tinysrgb&#038;h=650&#038;w=940\" alt=\"\u0686\u06cc\u062e\u0646\u06d2 \u06a9\u06d2 \u0641\u0648\u0627\u0626\u062f \u06a9\u0627 \u062a\u0635\u0648\u0631\u0627\u062a\u06cc \u0645\u0646\u0638\u0631\" title=\"\"><\/p>\n<p>\u06cc\u06c1 \u06a9\u0648\u0626\u06cc \u0645\u0630\u0627\u0642 \u0646\u06c1\u06cc\u06ba \u06c1\u06d2\u06d4 \u0633\u0627\u0626\u0646\u0633\u062f\u0627\u0646\u0648\u06ba \u0646\u06d2 \u062b\u0627\u0628\u062a \u06a9\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0686\u06cc\u062e\u0646\u06d2 \u0633\u06d2 \u062f\u0645\u0627\u063a \u0645\u06cc\u06ba \u0627\u06cc\u0646\u0688\u0648\u0631\u0641\u0646\u0632 \u062e\u0627\u0631\u062c \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062c\u0648 \u0642\u062f\u0631\u062a\u06cc \u062f\u0631\u062f \u06a9\u0634 \u0627\u062f\u0648\u06cc\u0627\u062a \u06a9\u06cc \u0637\u0631\u062d \u06a9\u0627\u0645 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0627\u06cc\u06a9 \u062a\u062d\u0642\u06cc\u0642 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642\u060c 70% \u0644\u0648\u06af\u0648\u06ba \u0646\u06d2 \u0686\u06cc\u062e\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0646\u0645\u0627\u06cc\u0627\u06ba <span style=\"color:#FF9800; font-weight:bold; text-decoration:underline;\">\u062a\u0646\u0627\u0624 \u0645\u06cc\u06ba \u06a9\u0645\u06cc<\/span> \u0645\u062d\u0633\u0648\u0633 \u06a9\u06cc\u06d4 \u06cc\u06c1 \u0648\u06c1\u06cc \u06a9\u06cc\u0645\u06cc\u06a9\u0644 \u06c1\u06d2 \u062c\u0648 \u062f\u0648\u0691\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f &#8220;\u0631\u0646\u0631\u0632 \u06c1\u0627\u0626\u06cc&#8221; \u06a9\u0627 \u0627\u062d\u0633\u0627\u0633 \u062f\u0644\u0627\u062a\u0627 \u06c1\u06d2\u060c \u0644\u06cc\u06a9\u0646 \u06cc\u06c1\u0627\u06ba \u0622\u067e \u06a9\u0648 \u062c\u0645 \u062c\u0627\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u0646\u06c1\u06cc\u06ba\u060c \u0628\u0633 \u0627\u06cc\u06a9 \u0627\u0686\u06be\u06cc \u0686\u06cc\u062e \u06a9\u0627\u0641\u06cc \u06c1\u06d2\u06d4<\/p>\n<p>\u0645\u06af\u0631 \u06cc\u06c1\u0627\u06ba \u0627\u06cc\u06a9 \u0627\u06c1\u0645 \u0633\u0648\u0627\u0644 \u067e\u06cc\u062f\u0627 \u06c1\u0648\u062a\u0627 \u06c1\u06d2: \u06a9\u06cc\u0627 \u0648\u0627\u0642\u0639\u06cc \u0686\u06cc\u062e\u0646\u0627 \u0627\u062a\u0646\u0627 \u0622\u0633\u0627\u0646 \u06c1\u06d2 \u062c\u062a\u0646\u0627 \u0644\u06af\u062a\u0627 \u06c1\u06d2\u061f \u06a9\u06cc\u0627 \u06c1\u0631 \u0686\u06cc\u062e \u0622\u067e \u06a9\u0648 \u0628\u06c1\u062a\u0631 \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u0627\u062a\u06cc \u06c1\u06d2\u060c \u06cc\u0627 \u0627\u0633 \u06a9\u0627 \u06a9\u0648\u0626\u06cc \u0637\u0631\u06cc\u0642\u06c1 \u06a9\u0627\u0631 \u06c1\u06d2\u061f \u0622\u0626\u06cc\u06d2\u060c \u0622\u062c \u06c1\u0645 <span style=\"color:#9C27B0; font-weight:bold; text-decoration:underline;\">\u0686\u06cc\u062e \u0627\u0648\u0631 \u062f\u0645\u0627\u063a<\/span> \u06a9\u06d2 \u0627\u0633 \u0639\u062c\u06cc\u0628 \u0631\u0634\u062a\u06d2 \u06a9\u0648 \u0633\u0645\u062c\u06be\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0627\u0648\u0631 \u062c\u0627\u0646\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u06a9\u0633 \u0637\u0631\u062d \u0627\u06cc\u06a9 \u0628\u06be\u0631\u067e\u0648\u0631 \u0686\u06cc\u062e \u0622\u067e \u06a9\u06cc \u0632\u0646\u062f\u06af\u06cc \u06a9\u0648 \u0628\u062f\u0644 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4<\/p>\n<p><img data-lazyloaded=\"1\" decoding=\"async\" loading=\"lazy\" style=\"display:block; margin:auto;\" src=\"https:\/\/images.pexels.com\/photos\/6788750\/pexels-photo-6788750.jpeg?auto=compress&#038;cs=tinysrgb&#038;h=650&#038;w=940\" alt=\"\u06a9\u06cc\u062a\u06be\u0627\u0631\u0679\u06a9 \u0634\u0648\u0631 \u06a9\u0627 \u062f\u0645\u0627\u063a\u06cc \u0639\u0645\u0644\" title=\"\"><\/p>\n<h2>\u06a9\u06cc\u0627 \u0686\u06cc\u062e \u0648\u0627\u0642\u0639\u06cc \u06a9\u0627\u0645 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u061f \u0633\u0627\u0626\u0646\u0633\u06cc \u062d\u0642\u06cc\u0642\u062a<\/h2>\n<p>\u0622\u0626\u06cc\u06d2 \u067e\u06c1\u0644\u06d2 \u06cc\u06c1 \u0633\u0645\u062c\u06be\u06cc\u06ba \u06a9\u06c1 \u062c\u0628 \u06c1\u0645 \u0686\u06cc\u062e\u062a\u06d2 \u06c1\u06cc\u06ba \u062a\u0648 \u062f\u0645\u0627\u063a \u0645\u06cc\u06ba \u06a9\u06cc\u0627 \u06c1\u0648\u062a\u0627 \u06c1\u06d2\u06d4 \u062c\u0628 \u0622\u067e \u0627\u0648\u0646\u0686\u06cc \u0622\u0648\u0627\u0632 \u0645\u06cc\u06ba \u0628\u0648\u0644\u062a\u06d2 \u06c1\u06cc\u06ba \u06cc\u0627 \u0686\u06cc\u062e\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062a\u0648 \u0622\u067e \u06a9\u0627 \u0627\u0645\u06cc\u06af\u0688\u0627\u0644\u0627 (\u062f\u0645\u0627\u063a \u06a9\u0627 \u0648\u06c1 \u062d\u0635\u06c1 \u062c\u0648 \u062e\u0648\u0641 \u0627\u0648\u0631 \u063a\u0635\u06d2 \u06a9\u0648 \u06a9\u0646\u0679\u0631\u0648\u0644 \u06a9\u0631\u062a\u0627 \u06c1\u06d2) \u0627\u06cc\u06a9\u0679\u06cc\u0648\u06cc\u0679 \u06c1\u0648\u062a\u0627 \u06c1\u06d2\u06d4 \u06cc\u06c1 \u0648\u06c1 \u0644\u0645\u062d\u06c1 \u06c1\u06d2 \u062c\u0628 <span style=\"color:#4ECDC4; font-weight:bold; text-decoration:underline;\">\u06a9\u06cc\u062a\u06be\u0627\u0631\u0679\u06a9 \u0634\u0648\u0631<\/span> \u067e\u06cc\u062f\u0627 \u06c1\u0648\u062a\u0627 \u06c1\u06d2\u060c \u0627\u0648\u0631 \u062f\u0645\u0627\u063a \u0627\u0633\u06d2 \u0627\u06cc\u06a9 \u0633\u06af\u0646\u0644 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u0644\u06cc\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 &#8220;\u062e\u0637\u0631\u06c1 \u0679\u0644 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4&#8221;<\/p>\n<p>\u0645\u06cc\u0631\u06d2 \u0627\u06cc\u06a9 \u062f\u0648\u0633\u062a\u060c \u0627\u062d\u0645\u062f\u060c \u062c\u0648 \u0627\u06cc\u06a9 \u0628\u0632\u0646\u0633 \u0645\u06cc\u0646 \u06c1\u06cc\u06ba\u060c \u0646\u06d2 \u0645\u062c\u06be\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0648\u06c1 \u06c1\u0631 \u0645\u06c1\u06cc\u0646\u06d2 \u06a9\u06d2 \u0622\u062e\u0631\u06cc \u062c\u0645\u0639\u06d2 \u06a9\u0648 \u0627\u067e\u0646\u06cc \u06af\u0627\u0691\u06cc \u0645\u06cc\u06ba \u0628\u06cc\u0679\u06be \u06a9\u0631\u060c \u062f\u0631\u0648\u0627\u0632\u06d2 \u0628\u0646\u062f \u06a9\u0631 \u06a9\u06d2\u060c \u067e\u0648\u0631\u06d2 \u062f\u0644 \u0633\u06d2 \u0686\u06cc\u062e\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0648\u06c1 \u06a9\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 &#8220;\u06cc\u06c1 \u0645\u06cc\u0631\u06cc \u062a\u06be\u0631\u0627\u067e\u06cc \u06c1\u06d2\u060c \u0628\u06be\u0627\u0626\u06cc\u06d4 \u0627\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0645\u06cc\u06ba \u062f\u0633 \u06a9\u067e \u0686\u0627\u0626\u06d2 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u062a\u0627\u0632\u06c1 \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u062a\u0627 \u06c1\u0648\u06ba\u06d4&#8221; \u06cc\u06c1 \u06a9\u0648\u0626\u06cc \u0645\u0628\u0627\u0644\u063a\u06c1 \u0646\u06c1\u06cc\u06ba\u060c \u0628\u0644\u06a9\u06c1 \u0627\u0633 \u06a9\u06d2 \u067e\u06cc\u0686\u06be\u06d2 \u062d\u0642\u06cc\u0642\u06cc \u0633\u0627\u0626\u0646\u0633 \u06c1\u06d2\u06d4<\/p>\n<p>\u062a\u062d\u0642\u06cc\u0642 \u0633\u06d2 \u067e\u062a\u06c1 \u0686\u0644\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0686\u06cc\u062e\u0646\u06d2 \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u06a9\u0648\u0631\u0679\u06cc\u0633\u0648\u0644 (\u062a\u0646\u0627\u0624 \u06a9\u0627 \u06c1\u0627\u0631\u0645\u0648\u0646) \u06a9\u06cc \u0633\u0637\u062d \u0645\u06cc\u06ba 30% \u062a\u06a9 \u06a9\u0645\u06cc \u0648\u0627\u0642\u0639 \u06c1\u0648\u062a\u06cc \u06c1\u06d2\u06d4 \u06cc\u06c1\u06cc \u0648\u062c\u06c1 \u06c1\u06d2 \u06a9\u06c1 \u06a9\u0686\u06be \u0645\u0627\u06c1\u0631\u06cc\u0646 \u0646\u0641\u0633\u06cc\u0627\u062a \u0627\u067e\u0646\u06d2 \u0645\u0631\u06cc\u0636\u0648\u06ba \u06a9\u0648 &#8220;\u0633\u0627\u0624\u0646\u0688 \u062a\u06be\u06cc\u0631\u0627\u067e\u06cc&#8221; \u06a9\u0627 \u0645\u0634\u0648\u0631\u06c1 \u062f\u06cc\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062c\u0633 \u0645\u06cc\u06ba \u0645\u0631\u06cc\u0636 \u0627\u067e\u0646\u06cc \u0622\u0648\u0627\u0632 \u06a9\u0648 \u0628\u0637\u0648\u0631 \u0622\u0644\u06c1 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4<\/p>\n<h3>\u0686\u06cc\u062e\u0646\u06d2 \u06a9\u06d2 \u0641\u0648\u0627\u0626\u062f: \u0635\u0631\u0641 \u0622\u0648\u0627\u0632 \u0646\u06c1\u06cc\u06ba\u060c \u0628\u0644\u06a9\u06c1 \u0639\u0644\u0627\u062c<\/h3>\n<p>\u0627\u0628 \u0633\u0648\u0627\u0644 \u06cc\u06c1 \u06c1\u06d2 \u06a9\u06c1 \u0622\u062e\u0631 \u0686\u06cc\u062e \u06a9\u06d2 <span style=\"color:#FF9F1C; font-weight:bold; text-decoration:underline;\">\u0686\u06cc\u062e\u0646\u06d2 \u06a9\u06d2 \u0641\u0648\u0627\u0626\u062f<\/span> \u06a9\u06cc\u0627 \u06c1\u06cc\u06ba\u061f \u0635\u0631\u0641 \u062a\u0646\u0627\u0624 \u06a9\u0645 \u06a9\u0631\u0646\u0627 \u06c1\u06cc \u0646\u06c1\u06cc\u06ba\u060c \u0628\u0644\u06a9\u06c1 \u0627\u0633 \u06a9\u06d2 \u0627\u0648\u0631 \u0628\u06be\u06cc \u0628\u06c1\u062a \u0633\u06d2 \u0627\u062b\u0631\u0627\u062a \u06c1\u06cc\u06ba \u062c\u0648 \u0622\u067e \u06a9\u0648 \u062d\u06cc\u0631\u0627\u0646 \u06a9\u0631 \u062f\u06cc\u06ba \u06af\u06d2\u06d4 \u06cc\u06c1\u0627\u06ba \u06a9\u0686\u06be \u0627\u06c1\u0645 \u0641\u0648\u0627\u0626\u062f \u06c1\u06cc\u06ba:<\/p>\n<ul>\n<li><b>\u0628\u0644\u0688 \u067e\u0631\u06cc\u0634\u0631 \u0645\u06cc\u06ba \u06a9\u0645\u06cc:<\/b> \u0627\u06cc\u06a9 \u062a\u062d\u0642\u06cc\u0642 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642\u060c \u0686\u06cc\u062e\u0646\u06d2 \u0633\u06d2 \u062f\u0644 \u06a9\u06cc \u062f\u06be\u0691\u06a9\u0646 \u0633\u0633\u062a \u06c1\u0648 \u062c\u0627\u062a\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0628\u0644\u0688 \u067e\u0631\u06cc\u0634\u0631 \u0645\u06cc\u06ba 10% \u062a\u06a9 \u06a9\u0645\u06cc \u0622\u062a\u06cc \u06c1\u06d2\u06d4<\/li>\n<li><b>\u0622\u0648\u0627\u0632 \u06a9\u06cc \u06c1\u0688\u06cc\u0648\u06ba \u06a9\u06cc \u0648\u0631\u0632\u0634:<\/b> \u0686\u06cc\u062e\u0646\u0627 \u0622\u067e \u06a9\u06cc \u0648\u0648\u06a9\u0644 \u06a9\u0648\u0631\u0688\u0632 \u06a9\u0648 \u0645\u0636\u0628\u0648\u0637 \u0628\u0646\u0627\u062a\u0627 \u06c1\u06d2\u060c \u0628\u0627\u0644\u06a9\u0644 \u0627\u0633\u06cc \u0637\u0631\u062d \u062c\u06cc\u0633\u06d2 \u062c\u0645 \u0645\u06cc\u06ba \u0648\u0632\u0646 \u0627\u0679\u06be\u0627\u0646\u06d2 \u0633\u06d2 \u067e\u0679\u06be\u06d2 \u0645\u0636\u0628\u0648\u0637 \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4<\/li>\n<li><b>\u0627\u06cc\u0646\u0688\u0648\u0631\u0641\u0646\u0632 \u06a9\u0627 \u0627\u062e\u0631\u0627\u062c:<\/b> \u06cc\u06c1 \u0648\u06c1\u06cc \u062e\u0648\u0634\u06cc \u06a9\u0627 \u06c1\u0627\u0631\u0645\u0648\u0646 \u06c1\u06d2 \u062c\u0648 \u0622\u067e \u06a9\u0648 \u0686\u06cc\u062e\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0627\u06cc\u06a9 \u0639\u062c\u06cc\u0628 \u0633\u06cc \u062e\u0648\u0634\u06cc \u062f\u06cc\u062a\u0627 \u06c1\u06d2\u06d4<\/li>\n<li><b>\u062c\u0630\u0628\u0627\u062a\u06cc \u0631\u06cc\u0644\u06cc\u0641:<\/b> \u062c\u0628 \u0622\u067e \u0686\u06cc\u062e\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062a\u0648 \u0622\u067e \u0627\u067e\u0646\u06d2 \u0627\u0646\u062f\u0631 \u06a9\u06d2 \u062f\u0628\u06d2 \u062c\u0630\u0628\u0627\u062a \u06a9\u0648 \u0628\u0627\u06c1\u0631 \u0646\u06a9\u0627\u0644 \u0631\u06c1\u06d2 \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062c\u0648 \u0622\u067e \u06a9\u0648 \u06c1\u0644\u06a9\u0627 \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u0627\u062a\u0627 \u06c1\u06d2\u06d4<\/li>\n<\/ul>\n<p>\u06a9\u0686\u06be \u0644\u0648\u06af \u06a9\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u0686\u06cc\u062e\u0646\u0627 \u0628\u062f\u062a\u0645\u06cc\u0632\u06cc \u06c1\u06d2\u060c \u0644\u06cc\u06a9\u0646 \u062d\u0642\u06cc\u0642\u062a \u06cc\u06c1 \u06c1\u06d2 \u06a9\u06c1 \u06cc\u06c1 \u0622\u067e \u06a9\u06cc \u0630\u06c1\u0646\u06cc \u0635\u062d\u062a \u06a9\u06d2 \u0644\u06cc\u06d2 \u0628\u06c1\u062a \u0636\u0631\u0648\u0631\u06cc \u06c1\u06d2\u06d4 2019 \u0645\u06cc\u06ba \u06a9\u06cc \u06af\u0626\u06cc \u0627\u06cc\u06a9 \u062a\u062d\u0642\u06cc\u0642 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642\u060c \u062c\u0646 \u0644\u0648\u06af\u0648\u06ba \u0646\u06d2 \u0628\u0627\u0642\u0627\u0639\u062f\u06af\u06cc \u0633\u06d2<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u06a9\u06cc\u0627 \u0622\u067e \u0646\u06d2 \u06a9\u0628\u06be\u06cc \u0645\u062d\u0633\u0648\u0633 \u06a9\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062f\u0644 \u0645\u06cc\u06ba \u062f\u0628\u0627 \u062f\u0628\u0627\u0624 \u0627\u062a\u0646\u0627 \u0628\u0691\u06be \u062c\u0627\u0626\u06d2 \u06a9\u06c1 \u0633\u0627\u0646\u0633 \u0644\u06cc\u0646\u0627 \u0628\u06be\u06cc \u0645\u0634\u06a9\u0644 \u06c1\u0648 \u062c\u0627\u0626\u06d2\u061f \u0648\u06c1 \u0644\u0645\u062d\u06c1 \u062c\u0628&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-1744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/indusherbal.com\/lang\/ur\/blog\/wp-json\/wp\/v2\/posts\/1744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indusherbal.com\/lang\/ur\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/indusherbal.com\/lang\/ur\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/indusherbal.com\/lang\/ur\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/indusherbal.com\/lang\/ur\/blog\/wp-json\/wp\/v2\/comments?post=1744"}],"version-history":[{"count":0,"href":"https:\/\/indusherbal.com\/lang\/ur\/blog\/wp-json\/wp\/v2\/posts\/1744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indusherbal.com\/lang\/ur\/blog\/wp-json\/wp\/v2\/media\/1743"}],"wp:attachment":[{"href":"https:\/\/indusherbal.com\/lang\/ur\/blog\/wp-json\/wp\/v2\/media?parent=1744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/indusherbal.com\/lang\/ur\/blog\/wp-json\/wp\/v2\/categories?post=1744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/indusherbal.com\/lang\/ur\/blog\/wp-json\/wp\/v2\/tags?post=1744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}